{"id":3471,"date":"2020-10-10T21:14:22","date_gmt":"2020-10-10T19:14:22","guid":{"rendered":"https:\/\/myparistouch.com\/?p=3471"},"modified":"2020-10-11T10:06:10","modified_gmt":"2020-10-11T08:06:10","slug":"que-faire-a-paris-cet-automne","status":"publish","type":"post","link":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/","title":{"rendered":"Que faire \u00e0 Paris cet automne?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb3.22&Prime;][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb3.25&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.6.2&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb]<\/p>\n<p>Cela fait bien longtemps que je n\u2019ai pas \u00e9crit un article avec des id\u00e9es de sorties pourtant j\u2019ai vu quelques expositions et participer \u00e0 quelque \u00e9v\u00e9nements comme la nuit blanche mais c\u2019est vrai que la motivation et l&rsquo;enthousiasme \u00e9taient un peu fan\u00e9es mais voil\u00e0 la vie continue et Paris \u00e0 toujours beaucoup \u00e0 offrir.<\/p>\n<p>Alors je vous propose d\u2019organiser un weekend autour d\u2019un th\u00e8me <strong>Paris et la mode<\/strong> mais attention il ne s\u2019agit pas d\u2019aller faire du shopping mais de d\u00e9couvrir ou red\u00e9couvrir une p\u00e9riode, une cr\u00e9atrice et un artiste iconique du Paris des ann\u00e9es 20 et 30.<\/p>\n<p><strong>Petit conseil pratique:<\/strong> quasiment tous les mus\u00e9es parisiens dans leur protocole de mesures sanitaires vous demande de r\u00e9server un cr\u00e9neau horaire en ligne alors dommage pour la spontan\u00e9it\u00e9 mais l\u2019avantage c\u2019est une visite dans des conditions plus s\u00e9curisante.<\/p>\n<h1>Expositions sur le th\u00e8me Paris et la mode<\/h1>\n<h2>\u00a0<\/h2>\n<h2>Man Ray et la Mode<\/h2>\n<p>Je vous propose de commencer par la visite de l\u2019exposition<a href=\"https:\/\/museeduluxembourg.fr\/en\/node\/6499\"> Man Ray et la mode<\/a> qui se tient au mus\u00e9e du Luxembourg jusqu\u2019au 17 janvier.\u00a0 2021.<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3476 alignright\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/096190D9-0198-4158-BA30-836B7671BDD8_1_105_c.jpeg\" alt=\"\" width=\"300\" height=\"370\" \/><\/p>\n<p>L\u2019exposition vous permet de d\u00e9couvrir une des facettes peu connue de cet artiste surr\u00e9aliste.\u00a0 Il fut tr\u00e8s pr\u00e9sent sur la sc\u00e8ne artistique et mondaine du Paris des ann\u00e9es 20 et 30. Mais Il est aussi un acteur cl\u00e9 de l\u2019invention de la photographie de mode.<\/p>\n<p>Vous suivrez\u00a0 ses rencontres, ses d\u00e9couvertes artistiques et techniques qu\u2019il a su transf\u00e9rer dans l\u2019univers de la photographie de mode, les femmes devenues c\u00e9l\u00e8bres qui ont\u00a0 jalonn\u00e9es son parcours, ses photos iconiques etc\u2026<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3478 alignleft\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/474897DC-D834-49F1-A8CB-590FCBE0C166_1_105_c.jpeg\" alt=\"\" width=\"374\" height=\"499\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Pour prolonger l\u2019exposition, plusieurs options.<\/p>\n<p>Vous, pr\u00e9cipiter sur ARTE.TV pour regarder les deux documentaires consacr\u00e9s \u00e0 Lee Miller qui fut l\u2019assistante, le mod\u00e8le, la muse et amante de Man Ray pendant quelques ann\u00e9es.<\/p>\n<p>Les documentaires sont vraiment formidables.<\/p>\n<p><a href=\"https:\/\/www.arte.tv\/fr\/videos\/092125-000-A\/lee-miller-mannequin-et-photographe-de-guerre\/\">Lee Miller: Mannequin et photographe de Guerre<\/a> : disponible en replay jusqu\u2019au 27 novembre.<\/p>\n<p><a href=\"https:\/\/www.arte.tv\/fr\/videos\/079434-003-A\/l-amour-a-l-oeuvre-lee-miller-et-man-ray\/\">L\u2019amour \u00e0 l\u2019Oeuvre : Man Ray et Lee Miller<\/a>: disponible en replay jusqu\u2019au 30 octobre.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Harper&rsquo;s Bazar, Premier Magazine de Mode<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3496 alignnone size-full\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/588AC09C-E214-424D-9767-8445B7091903_1_105_c.jpeg\" alt=\"\" width=\"886\" height=\"886\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/588AC09C-E214-424D-9767-8445B7091903_1_105_c.jpeg 886w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/588AC09C-E214-424D-9767-8445B7091903_1_105_c-480x480.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 886px, 100vw\" \/>Pour poursuivre cette immersion dans le monde de la photographie de Mode, il vous suffit de vous rendre au Mus\u00e9e des Arts d\u00e9coratifs avant le 3 janvier pour aller admirer l\u2019exposition <a href=\"https:\/\/madparis.fr\/francais\/musees\/musee-des-arts-decoratifs\/expositions\/expositions-en-cours\/harper-s-bazaar-premier-magazine-de-mode\/\">Harper&rsquo;s Bazar,\u00a0 Premier Magazine de mode.<\/a><\/p>\n<p>Man Ray a r\u00e9ellement d\u00e9but\u00e9 sa carri\u00e8re de photographe de Mode au Harper&rsquo;s Bazar.<\/p>\n<p>J\u2019ai eu le bonheur de visiter cette exposition juste avant le confinement, elle pr\u00e9sente l\u2019histoire du magazine de sa cr\u00e9ation \u00e0 aujourd\u2019hui \u00e0 travers les plus fameuses de ses couvertures mais \u00e9galement avec 6O des mod\u00e8les les plus iconiques pr\u00e9sent\u00e9s dans le magazine.<\/p>\n<p>Important : En pr\u00e9sentant votre billet de l\u2019exposition de Man Ray vous aurez droit \u00e0 une r\u00e9duction sur l\u2019exposition du mus\u00e9e des Arts d\u00e9coratifs.<\/p>\n<h2>Gabrielle Chanel, Manifeste de Mode<\/h2>\n<p>L\u2019autre exposition du moment qui vient en \u00e9cho \u00e0\u00a0 celle de Man Ray, c\u2019est l\u2019exposition sur <a href=\"https:\/\/madparis.fr\/francais\/musees\/musee-des-arts-decoratifs\/expositions\/expositions-en-cours\/harper-s-bazaar-premier-magazine-de-mode\/\">Gabrielle Chanel. Manifeste de Mode<\/a>,\u00a0 qui vient de d\u00e9buter au Mus\u00e9e Galliera : mus\u00e9e de la mode de Paris qui vient de rouvrir apr\u00e8s plusieurs mois de travaux.<\/p>\n<p>Je ne peux pas vous en dire plus car je ne l\u2019ai pas encore visit\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<h1>Pause gourmande:<\/h1>\n<p>Tr\u00e8s souvent avant ou apr\u00e8s une exposition je m\u2019offre une pause gourmande, quand je suis accompagn\u00e9e, c&rsquo;est l\u2019occasion d\u2019\u00e9changer nos impressions sur l&rsquo;exposition et sinon c\u2019est le moment de reprendre des forces et de se relaxer et faire honneur au plaisir parisien de d\u00e9guster une p\u00e2tisserie, une bonne tasse de chocolat chaud ou bien un bon th\u00e9 fumant.<\/p>\n<p>Je vais vous confier quelques unes de mes adresses f\u00e9tiches pour une d\u00e9licieuse pause gourmande.<\/p>\n<h2>Jardin du Luxembourg<\/h2>\n<p>Quand on va voir une exposition au Mus\u00e9e du Luxembourg, la solution qui semblerait la plus \u00e9vidente pour une pause gourmande serait de se rendre au caf\u00e9<a href=\"https:\/\/www.angelina-paris.fr\/fr\/mademoiselle-angelina\"> Mademoiselle Angelina <\/a>qui jouxte le mus\u00e9e et m\u00eame si j\u2019aime beaucoup cette adresse, ce n\u2019est pas celle-ci dont je souhaitais vous parler mais de <a href=\"http:\/\/treizeaujardin.com\/\">13 au Jardin<\/a> qui remplace le coffee shop du 16 rue des Saint P\u00e8res 13 a Baker\u2019s dozen. Le nouveau coffeeshop est bien plus spacieux et propose une tr\u00e8s sympathique terrasse juste en face du jardin du Luxembourg.<\/p>\n<p>On peut trouver les grands succ\u00e8s de la p\u00e2tisserie am\u00e9ricaine : Carrot Cakes, Brownies, Cheesecakes etc\u2026 <a href=\"http:\/\/tre13e.paris\/menudesserts.php?L=fr\">leur carte sal\u00e9e<\/a> est \u00e9galement extr\u00eamement all\u00e9chante. Les boissons sont aussi tr\u00e8s nombreuses. je ne peux que recommander le chocolat chaud tr\u00e8s cr\u00e9meux et gourmand.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3482\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/979890AA-0E02-455F-970C-2C8D99CB38E7_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/979890AA-0E02-455F-970C-2C8D99CB38E7_1_105_c.jpeg 768w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/979890AA-0E02-455F-970C-2C8D99CB38E7_1_105_c-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><\/p>\n<h2>Rue de Rivoli<\/h2>\n<p>Je ne peux pas me contenter d\u2019une seule adresse alors ce sera deux adresses aux ambiances et aux saveurs tr\u00e8s diff\u00e9rentes.<\/p>\n<p><a href=\"http:\/\/www.sebastiengaudard.com\/patisseries\">Salon de th\u00e9 S\u00e9bastien Gaudard <\/a>\u00a01 rue des Pyramides: c\u2019est le nom d\u2019un chef p\u00e2tissier qui propose des grands classiques de la p\u00e2tisserie fran\u00e7aise : Saint Honor\u00e9, choux \u00e0 la cr\u00e8me, mille feuilles etc\u2026 les go\u00fbt sont authentiques et d\u00e9licats. Le salon de th\u00e9 est tout petit on dirait un petit boudoir, le service est agr\u00e9able. L\u2019atmosph\u00e8re a un c\u00f4t\u00e9 peu d\u00e9suet mais fort agr\u00e9able.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3486\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/77682324-5A40-4F61-8444-FE59698D3852_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/77682324-5A40-4F61-8444-FE59698D3852_1_105_c.jpeg 768w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/77682324-5A40-4F61-8444-FE59698D3852_1_105_c-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><\/p>\n<p><a href=\"https:\/\/www.lestube.fr\/catalogue-de-commande\/\">Le Stube<\/a> 31 rue de Richelieu: ici on trouve le meilleure de la gastronomie allamande. L\u2019adresse est connue pour ses g\u00e2teaux, les for\u00eats noires, les Linzetorte, les Apfeltorte, les gateaux au fromage blanc, les Sachertorte&#8230;. Tout est tr\u00e8s bon. On y trouve des bionades, du vin chaud l\u2019hiver et les petits g\u00e2teaux de No\u00ebl pendant la saison. Le lieu est assez moderne pas tr\u00e8s cosy mais sympathique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3484\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/08BC2F52-B094-4508-AF11-FFB10C57F9F9_1_105_c.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/08BC2F52-B094-4508-AF11-FFB10C57F9F9_1_105_c.jpeg 1024w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/08BC2F52-B094-4508-AF11-FFB10C57F9F9_1_105_c-980x735.jpeg 980w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/08BC2F52-B094-4508-AF11-FFB10C57F9F9_1_105_c-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/p>\n<h2>Palais Galliera<\/h2>\n<p>A chaque fois que je vais voir une exposition au mus\u00e9e Galliera ou que je vais au Mus\u00e9e d\u2019Art Moderne de Paris, je fais un petit tour \u00e0 la<a href=\"https:\/\/www.gourmand-croquant.com\/fr\/content\/6-nos-adresses\"> P\u00e2tisserie de Cyril Lignac<\/a> qui se trouve au 2 rue de Chaillot, tr\u00e8s difficile de faire son choix, car tout est tr\u00e8s app\u00e9tissant mais mes recommandations seraient le flan au chocolat, l\u2019\u00e9clair au caramel au beurre sal\u00e9 et la Baba au Rhum.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3490\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/A4A2CAD8-29D6-47C2-8905-012BB7D5F016_1_105_c.jpeg\" alt=\"\" width=\"793\" height=\"991\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/A4A2CAD8-29D6-47C2-8905-012BB7D5F016_1_105_c.jpeg 793w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/A4A2CAD8-29D6-47C2-8905-012BB7D5F016_1_105_c-480x600.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 793px, 100vw\" \/><\/p>\n<p>Quand il fait beau l&rsquo;id\u00e9al c\u2019est d\u2019aller dans le Square du Palais Galliera pour d\u00e9guster votre g\u00e2teau, viennoiserie ou toute autre gourmandise. Autre option c\u2019est d\u2019aller vous installer dans le caf\u00e9 qui jouxte la p\u00e2tisserie. Ils acceptent que vous consommiez vos p\u00e2tisseries sur place.<\/p>\n<p>Apr\u00e8s cette pause gourmande, vous aurez le choix soit de faire un tour au Jardin du Luxembourg ou au jardin des Tuileries et si vous allez au mus\u00e9e Galliera je vous conseille d\u2019aller admirer la vue sur la Tour Eiffel depuis la terrasse du Palais de Tokyo.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3498\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/8478915B-F943-4423-A4DA-95949B31AB43_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/8478915B-F943-4423-A4DA-95949B31AB43_1_105_c.jpeg 768w, https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/8478915B-F943-4423-A4DA-95949B31AB43_1_105_c-480x640.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 768px, 100vw\" \/><\/p>\n<p>N&rsquo;h\u00e9sitez pas \u00e0 me laisser vos commentaires sur les expositions ou les salons de th\u00e9. Bon weekend \u00e0\u00a0 tous !!!<\/p>\n<p>&nbsp;<\/p>\n<p>Musae du Luxembourg : 19 rue de Vaugirard Paris 06<\/p>\n<p>Mus\u00e9 des Arts D\u00e9couratifs: 107 rue de Rivoli Paris 01<\/p>\n<p>Mus\u00e9e Galliera: <span class=\"LrzXr\">10 Avenue Pierre 1er de Serbie, <\/span>Paris 16<\/p>\n<p>Mademoiselle Angelina: 19 rue de Vaugirard Paris 06<\/p>\n<p>Treize Au Jardin : 5 rue de M\u00e9dicis Paris 06<\/p>\n<p>Sebastien Gaudard Salon de th\u00e9: 1 rue des Pyramides Paris 01<\/p>\n<p>Le Stube : <span class=\"w8qArf\"><span class=\"LrzXr\">31 Rue de Richelieu Paris 01<\/span><\/span><\/p>\n<p>P\u00e2tisserie Cyril Lignac : <span class=\"LrzXr\">2 Rue de Chaillot, Paris 16<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela fait bien longtemps que je n\u2019ai pas \u00e9crit un article avec des id\u00e9es de sorties pourtant j\u2019ai vu quelques expositions et participer \u00e0 quelque \u00e9v\u00e9nements comme la nuit blanche mais c\u2019est vrai que la motivation et l&rsquo;enthousiasme \u00e9taient un peu fan\u00e9es mais voil\u00e0 la vie continue et Paris \u00e0 toujours beaucoup \u00e0 offrir. Alors [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Cela fait bien longtemps que je n\u2019ai pas \u00e9crit un article avec des id\u00e9es de sorties pourtant j\u2019ai vu quelques expositions et participer \u00e0 quelque \u00e9v\u00e9nements comme la nuit blanche mais c\u2019est vrai que la motivation et l'enthousiasme \u00e9taient un peu fan\u00e9es mais voil\u00e0 la vie continue et Paris \u00e0 toujours beaucoup \u00e0 offrir.\r\n\r\nAlors je vous propose d\u2019organiser un weekend autour d\u2019un th\u00e8me <strong>Paris et la mode<\/strong> mais attention il ne s\u2019agit pas d\u2019aller faire du shopping mais de d\u00e9couvrir ou red\u00e9couvrir une p\u00e9riode, une cr\u00e9atrice et un artiste iconique du Paris des ann\u00e9es 20 et 30.\r\n\r\nPetit conseil pratique: quasiment tous les mus\u00e9es parisiens dans leur protocole de mesures sanitaires vous demande de r\u00e9server un cr\u00e9neau horaire en ligne alors dommage pour la spontan\u00e9it\u00e9 mais l\u2019avantage c\u2019est une visite dans des conditions plus s\u00e9curisante.\r\n<h1>Expositions sur le th\u00e8me Paris et la mode<\/h1>\r\n<h2><\/h2>\r\n<h2>Man Ray et la Mode<\/h2>\r\nJe vous propose de commencer par la visite de l\u2019exposition<a href=\"https:\/\/museeduluxembourg.fr\/en\/node\/6499\"> Man Ray et la mode<\/a> qui se tient au mus\u00e9e du Luxembourg jusqu\u2019au 17 janvier.\u00a0 2021.<img class=\"wp-image-3476 alignright\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/096190D9-0198-4158-BA30-836B7671BDD8_1_105_c.jpeg\" alt=\"\" width=\"300\" height=\"370\" \/>\r\n\r\nL\u2019exposition vous permet de d\u00e9couvrir une des facettes peu connue de cet artiste surr\u00e9aliste.\u00a0 Il fut tr\u00e8s pr\u00e9sent sur la sc\u00e8ne artistique et mondaine du Paris des ann\u00e9es 20 et 30. Mais Il est aussi un acteur cl\u00e9 de l\u2019invention de la photographie de mode.\r\n\r\nVous suivrez\u00a0 ses rencontres, ses d\u00e9couvertes artistiques et techniques qu\u2019il a su transf\u00e9rer dans l\u2019univers de la photographie de mode, les\r\n\r\nfemmes devenues c\u00e9l\u00e8bres qui ont\u00a0 jalonn\u00e9es son parcours, ses photos iconiques etc\u2026\r\n\r\n<img class=\"wp-image-3478 alignleft\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/474897DC-D834-49F1-A8CB-590FCBE0C166_1_105_c.jpeg\" alt=\"\" width=\"374\" height=\"499\" \/>\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n\r\nPour prolonger l\u2019exposition, plusieurs options.\r\n\r\nVous, pr\u00e9cipiter sur ARTE.TV pour regarder les deux documentaires consacr\u00e9s \u00e0 Lee Miller qui fut l\u2019assistante, le mod\u00e8le, la muse et amante de Man Ray pendant quelques ann\u00e9es.\r\n\r\nLes documentaires sont vraiment formidables.\r\n\r\n<a href=\"https:\/\/www.arte.tv\/fr\/videos\/092125-000-A\/lee-miller-mannequin-et-photographe-de-guerre\/\">Lee Miller: Mannequin et photographe de Guerre<\/a> : disponible en replay jusqu\u2019au 27 novembre\r\n\r\n<a href=\"https:\/\/www.arte.tv\/fr\/videos\/079434-003-A\/l-amour-a-l-oeuvre-lee-miller-et-man-ray\/\">L\u2019amour \u00e0 l\u2019Oeuvre : Man Ray et Lee Miller<\/a>: disponible en replay jusqu\u2019au 30 octobre\r\n<h2>Harper's Bazar, Premier Magazine de Mode<\/h2>\r\n<img class=\"alignnone size-full wp-image-3496\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/588AC09C-E214-424D-9767-8445B7091903_1_105_c.jpeg\" alt=\"\" width=\"886\" height=\"886\" \/>L\u2019autre option: vous rendre au Mus\u00e9e des Arts d\u00e9coratifs pour aller admirer l\u2019exposition <a href=\"https:\/\/madparis.fr\/francais\/musees\/musee-des-arts-decoratifs\/expositions\/expositions-en-cours\/harper-s-bazaar-premier-magazine-de-mode\/\">Harper's Bazar,\u00a0 Premier Magazine de mode<\/a> qui se tient au Mus\u00e9e des Arts d\u00e9coratifs jusqu\u2019au 3 janvier.\r\n\r\nMan Ray a r\u00e9ellement d\u00e9but\u00e9 sa carri\u00e8re de photographe de Mode au Harper's Bazar.\r\n\r\nJ\u2019ai eu le bonheur de visiter cette exposition juste avant le confinement, elle pr\u00e9sente l\u2019histoire du magazine de sa cr\u00e9ation \u00e0 aujourd\u2019hui \u00e0 travers les plus fameuses de ses couvertures mais \u00e9galement avec 6O des mod\u00e8les les plus iconiques pr\u00e9sent\u00e9s dans le magazine.\r\n\r\nImportant : En pr\u00e9sentant votre billet de l\u2019exposition de Man Ray vous aurez droit \u00e0 une r\u00e9duction sur l\u2019exposition du mus\u00e9e des Arts d\u00e9coratifs.\r\n<h2>Gabrielle Chanel, Manifeste de Mode<\/h2>\r\nL\u2019autre exposition du moment qui vient en \u00e9cho \u00e0\u00a0 celle de Man Ray, c\u2019est l\u2019exposition sur <a href=\"https:\/\/madparis.fr\/francais\/musees\/musee-des-arts-decoratifs\/expositions\/expositions-en-cours\/harper-s-bazaar-premier-magazine-de-mode\/\">Gabrielle Chanel. Manifeste de Mode<\/a>,\u00a0 qui vient de d\u00e9buter au Mus\u00e9e Galliera : mus\u00e9e de la mode de Paris qui vient de rouvrir apr\u00e8s plusieurs mois de travaux.\r\n\r\nJe ne peux pas vous en dire plus car je ne l\u2019ai pas encore visit\u00e9e.\r\n\r\n\u00a0\r\n<h1>Pause gourmande:<\/h1>\r\nTr\u00e8s souvent avant ou apr\u00e8s une exposition je m\u2019offre une pause gourmande, quand je suis accompagn\u00e9e, c'est l\u2019occasion d\u2019\u00e9changer nos impressions sur l'exposition et sinon c\u2019est le moment de reprendre des forces et de se relaxer et faire honneur au plaisir parisien de d\u00e9guster une p\u00e2tisserie, une bonne tasse de chocolat chaud ou bien un bon th\u00e9 fumant.\r\n\r\nAlors je vais vous confier quelques unes de mes adresses f\u00e9tiches pour une d\u00e9licieuse pause gourmande.\r\n<h2>Jardin du Luxembourg<\/h2>\r\nQuand on va voir une exposition au Mus\u00e9e du Luxembourg, la solution qui semblerait la plus \u00e9vidente pour une pause gourmande serait de se rendre au caf\u00e9<a href=\"https:\/\/www.angelina-paris.fr\/fr\/mademoiselle-angelina\"> Mademoiselle Angelina <\/a>qui jouxte le mus\u00e9e et m\u00eame si j\u2019aime beaucoup cette adresse, ce n\u2019est pas celle-ci dont je souhaitais vous parler mais de <a href=\"http:\/\/treizeaujardin.com\/\">13 au Jardin<\/a> qui remplace le coffee shop du 16 rue des Saint P\u00e8res 13 a Baker\u2019s dozen. Le nouveau coffeeshop est bien plus spacieux et propose une tr\u00e8s sympathique terrasse juste en face du jardin du Luxembourg.\r\n\r\nOn peut trouver les grands succ\u00e8s de la p\u00e2tisserie am\u00e9ricaine : Carrot Cakes, Brownies, Cheesecakes etc\u2026 <a href=\"http:\/\/tre13e.paris\/menudesserts.php?L=fr\">leur carte sal\u00e9e<\/a> est \u00e9galement extr\u00eamement all\u00e9chante. Les boissons sont aussi tr\u00e8s nombreuses. je ne peux que recommander le chocolat chaud tr\u00e8s cr\u00e9meux et gourmand.\r\n\r\n<img class=\"alignnone size-full wp-image-3482\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/979890AA-0E02-455F-970C-2C8D99CB38E7_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" \/>\r\n<h2>Rue de Rivoli<\/h2>\r\nJe ne peux pas me contenter d\u2019une seule adresse alors ce sera deux adresses aux ambiances et aux saveurs tr\u00e8s diff\u00e9rentes.\r\n\r\n<a href=\"http:\/\/www.sebastiengaudard.com\/patisseries\">Salon de th\u00e9 S\u00e9bastien Gaudard <\/a>\u00a01 rue des Pyramides: c\u2019est le nom d\u2019un chef p\u00e2tissier qui propose des grands classiques de la p\u00e2tisserie fran\u00e7aise : Saint Honor\u00e9, choux \u00e0 la cr\u00e8me, mille feuilles etc\u2026 les go\u00fbt sont authentiques et d\u00e9licats. Le salon de th\u00e9 est tout petit on dirait un petit boudoir, le service est agr\u00e9able. L\u2019atmosph\u00e8re a un c\u00f4t\u00e9 peu d\u00e9suet mais fort agr\u00e9able. Pas contre les prix sont un peu \u00e9lev\u00e9s.\r\n\r\n<img class=\"alignnone size-full wp-image-3486\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/77682324-5A40-4F61-8444-FE59698D3852_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" \/>\r\n\r\n<a href=\"https:\/\/www.lestube.fr\/catalogue-de-commande\/\">Le Stube<\/a> 31 rue de Richelieu: ici on trouve le meilleure de la gastronomie allamande. L\u2019adresse est connue pour ses g\u00e2teaux, les for\u00eats noires, les Linzetorte, les Apfeltorte, les gateaux au fromage blanc, les Sachertorte.... Tout est tr\u00e8s bon. On y trouve des bionades, du vin chaud l\u2019hiver et les petits g\u00e2teaux de No\u00ebl pendant la saison. Le lieu est assez moderne pas tr\u00e8s cosy mais sympathique.\r\n\r\n<img class=\"alignnone size-full wp-image-3484\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/08BC2F52-B094-4508-AF11-FFB10C57F9F9_1_105_c.jpeg\" alt=\"\" width=\"1024\" height=\"768\" \/>\r\n<h2>Palais Galliera<\/h2>\r\nA chaque fois que je vais voir une exposition au mus\u00e9e Galliera ou que je vais au Mus\u00e9e d\u2019Art Moderne de Paris, je fais un petit tour \u00e0 la<a href=\"https:\/\/www.gourmand-croquant.com\/fr\/content\/6-nos-adresses\"> P\u00e2tisserie de Cyril Lignac<\/a> qui se trouve au 2 rue de Chaillot, tr\u00e8s difficile de faire son choix, car tout est tr\u00e8s app\u00e9tissant mais mes recommandations seraient le flan au chocolat, l\u2019\u00e9clair au caramel au beurre sal\u00e9 et la Baba au Rhum.\r\n\r\n<img class=\"alignnone size-full wp-image-3490\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/A4A2CAD8-29D6-47C2-8905-012BB7D5F016_1_105_c.jpeg\" alt=\"\" width=\"793\" height=\"991\" \/>\r\n\r\nQuand il fait beau l'id\u00e9al c\u2019est d\u2019aller dans le Square du Palais Galliera pour d\u00e9guster votre g\u00e2teau, viennoiserie ou toute autre gourmandise. Autre option c\u2019est d\u2019aller vous installer dans le caf\u00e9 qui jouxte la p\u00e2tisserie. Ils acceptent que vous consommiez vos p\u00e2tisseries sur place.\r\n\r\nApr\u00e8s cette pause gourmande, vous aurez le choix soit de faire un tour au Jardin du Luxembourg ou au jardin des Tuileries et si vous allez au mus\u00e9e Galliera je vous conseille d\u2019aller admirer la vue sur la Tour Eiffel depuis la terrasse du Palais de Tokyo.<img class=\"alignnone size-full wp-image-3498\" src=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/8478915B-F943-4423-A4DA-95949B31AB43_1_105_c.jpeg\" alt=\"\" width=\"768\" height=\"1024\" \/>\r\n\r\nN'h\u00e9sitez pas \u00e0 me laisser vos commentaires sur les expositions ou les salons de th\u00e9. Bon weekend \u00e0\u00a0 tous !!!","_et_gb_content_width":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[6,20,17],"tags":[],"class_list":["post-3471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expatrie","category-que-faire-a-paris-2","category-visiter-paris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Que faire \u00e0 Paris cet automne? - MyParisTouch<\/title>\n<meta name=\"description\" content=\"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que faire \u00e0 Paris cet automne? - MyParisTouch\" \/>\n<meta property=\"og:description\" content=\"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/\" \/>\n<meta property=\"og:site_name\" content=\"MyParisTouch\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MyParisTouch\/?ref=bookmarks\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-10T19:14:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-11T08:06:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Delphine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BriereDelphine\" \/>\n<meta name=\"twitter:site\" content=\"@BriereDelphine\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Delphine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/\"},\"author\":{\"name\":\"Delphine\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#\\\/schema\\\/person\\\/4d72917c43c79cf891604e0b8558c144\"},\"headline\":\"Que faire \u00e0 Paris cet automne?\",\"datePublished\":\"2020-10-10T19:14:22+00:00\",\"dateModified\":\"2020-10-11T08:06:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/\"},\"wordCount\":1337,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/34F9A242-B044-4D49-8543-E4145A97622C.jpg\",\"articleSection\":[\"Expatri\u00e9\",\"Que faire \u00e0 Paris ?\",\"Visiter Paris\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/\",\"url\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/\",\"name\":\"Que faire \u00e0 Paris cet automne? - MyParisTouch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/34F9A242-B044-4D49-8543-E4145A97622C.jpg\",\"datePublished\":\"2020-10-10T19:14:22+00:00\",\"dateModified\":\"2020-10-11T08:06:10+00:00\",\"description\":\"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#primaryimage\",\"url\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/34F9A242-B044-4D49-8543-E4145A97622C.jpg\",\"contentUrl\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/34F9A242-B044-4D49-8543-E4145A97622C.jpg\",\"width\":2048,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/que-faire-a-paris-cet-automne\\\/3471\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que faire \u00e0 Paris cet automne?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/\",\"name\":\"MyParisTouch\",\"description\":\"Accompagnement des expatri\u00e9s \u00e0 Paris\",\"publisher\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#organization\",\"name\":\"MyParisTouch\",\"url\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-mpt-233x300-1.png\",\"contentUrl\":\"https:\\\/\\\/myparistouch.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-mpt-233x300-1.png\",\"width\":233,\"height\":300,\"caption\":\"MyParisTouch\"},\"image\":{\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MyParisTouch\\\/?ref=bookmarks\",\"https:\\\/\\\/x.com\\\/BriereDelphine\",\"https:\\\/\\\/www.instagram.com\\\/myparistouch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/delphine-briere\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/myparistouch.com\\\/fr\\\/#\\\/schema\\\/person\\\/4d72917c43c79cf891604e0b8558c144\",\"name\":\"Delphine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g\",\"caption\":\"Delphine\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que faire \u00e0 Paris cet automne? - MyParisTouch","description":"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/","og_locale":"fr_FR","og_type":"article","og_title":"Que faire \u00e0 Paris cet automne? - MyParisTouch","og_description":"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode","og_url":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/","og_site_name":"MyParisTouch","article_publisher":"https:\/\/www.facebook.com\/MyParisTouch\/?ref=bookmarks","article_published_time":"2020-10-10T19:14:22+00:00","article_modified_time":"2020-10-11T08:06:10+00:00","og_image":[{"width":2048,"height":2048,"url":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg","type":"image\/jpeg"}],"author":"Delphine","twitter_card":"summary_large_image","twitter_creator":"@BriereDelphine","twitter_site":"@BriereDelphine","twitter_misc":{"\u00c9crit par":"Delphine","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#article","isPartOf":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/"},"author":{"name":"Delphine","@id":"https:\/\/myparistouch.com\/fr\/#\/schema\/person\/4d72917c43c79cf891604e0b8558c144"},"headline":"Que faire \u00e0 Paris cet automne?","datePublished":"2020-10-10T19:14:22+00:00","dateModified":"2020-10-11T08:06:10+00:00","mainEntityOfPage":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/"},"wordCount":1337,"commentCount":0,"publisher":{"@id":"https:\/\/myparistouch.com\/fr\/#organization"},"image":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#primaryimage"},"thumbnailUrl":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg","articleSection":["Expatri\u00e9","Que faire \u00e0 Paris ?","Visiter Paris"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/","url":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/","name":"Que faire \u00e0 Paris cet automne? - MyParisTouch","isPartOf":{"@id":"https:\/\/myparistouch.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#primaryimage"},"image":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#primaryimage"},"thumbnailUrl":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg","datePublished":"2020-10-10T19:14:22+00:00","dateModified":"2020-10-11T08:06:10+00:00","description":"options pour organiser son weekend \u00e0 Paris sur le th\u00e8me de la mode","breadcrumb":{"@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#primaryimage","url":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg","contentUrl":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/10\/34F9A242-B044-4D49-8543-E4145A97622C.jpg","width":2048,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/myparistouch.com\/fr\/que-faire-a-paris-cet-automne\/3471\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/myparistouch.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Que faire \u00e0 Paris cet automne?"}]},{"@type":"WebSite","@id":"https:\/\/myparistouch.com\/fr\/#website","url":"https:\/\/myparistouch.com\/fr\/","name":"MyParisTouch","description":"Accompagnement des expatri\u00e9s \u00e0 Paris","publisher":{"@id":"https:\/\/myparistouch.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myparistouch.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/myparistouch.com\/fr\/#organization","name":"MyParisTouch","url":"https:\/\/myparistouch.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/myparistouch.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/02\/logo-mpt-233x300-1.png","contentUrl":"https:\/\/myparistouch.com\/wp-content\/uploads\/2020\/02\/logo-mpt-233x300-1.png","width":233,"height":300,"caption":"MyParisTouch"},"image":{"@id":"https:\/\/myparistouch.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MyParisTouch\/?ref=bookmarks","https:\/\/x.com\/BriereDelphine","https:\/\/www.instagram.com\/myparistouch\/","https:\/\/www.linkedin.com\/in\/delphine-briere"]},{"@type":"Person","@id":"https:\/\/myparistouch.com\/fr\/#\/schema\/person\/4d72917c43c79cf891604e0b8558c144","name":"Delphine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/43c37be066e7c041509f7ad69a4ae68dd982e91658106da4b25e4e85f04aeb98?s=96&d=mm&r=g","caption":"Delphine"}}]}},"_links":{"self":[{"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/posts\/3471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/comments?post=3471"}],"version-history":[{"count":0,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/posts\/3471\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/media\/3473"}],"wp:attachment":[{"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/media?parent=3471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/categories?post=3471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/myparistouch.com\/fr\/wp-json\/wp\/v2\/tags?post=3471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}